{"id":7434,"date":"2025-01-15T14:04:56","date_gmt":"2025-01-15T14:04:56","guid":{"rendered":"https:\/\/tagesmutter-vellmar.de\/?page_id=7434"},"modified":"2025-02-05T11:11:33","modified_gmt":"2025-02-05T11:11:33","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/tagesmutter-vellmar.de\/index.php\/datenschutzerklaerung\/","title":{"rendered":"Daten\u00adschutz\u00ader\u00adkl\u00e4\u00adrung"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Daten\u00adschutz\u00ader\u00adkl\u00e4\u00adrung auf einen&nbsp;Blick<\/h3>\n\n\n\n<p><strong>All\u00adge\u00admeine Hin\u00adweise<\/strong><br>Die fol\u00adgen\u00adden Hin\u00adweise geben einen ein\u00adfa\u00adchen \u00dcber\u00adblick dar\u00ad\u00fcber, was mit Ihren per\u00adso\u00adnen\u00adbe\u00adzo\u00adge\u00adnen Daten pas\u00adsiert, wenn Sie unsere Web\u00adsite besu\u00adchen. Per\u00adso\u00adnen\u00adbe\u00adzo\u00adgene Daten sind alle Daten, mit denen Sie per\u00ads\u00f6n\u00adlich iden\u00adti\u00adfi\u00adziert wer\u00adden k\u00f6n\u00adnen. Aus\u00adf\u00fchr\u00adli\u00adche Infor\u00adma\u00adtio\u00adnen zum Thema Daten\u00adschutz ent\u00adneh\u00admen Sie unse\u00adrer unter die\u00adsem Text auf\u00adge\u00adf\u00fchr\u00adten Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Daten\u00ader\u00adfas\u00adsung auf unse\u00adrer Website<\/strong><\/h3>\n\n\n\n<p><strong>Wer ist ver\u00adant\u00adwort\u00adlich f\u00fcr die Daten\u00ader\u00adfas\u00adsung auf die\u00adser Web\u00adsite?<br><\/strong>Die Daten\u00adver\u00adar\u00adbei\u00adtung auf die\u00adser Web\u00adsite erfolgt durch den Web\u00adsite\u00adbe\u00adtrei\u00adber. Des\u00adsen Kon\u00adtakt\u00adda\u00adten k\u00f6n\u00adnen Sie dem Impres\u00adsum die\u00adser Web\u00adsite entnehmen.<\/p>\n\n\n\n<p><strong>Wie erfas\u00adsen wir Ihre Daten?<br><\/strong>Ihre Daten wer\u00adden zum einen dadurch erho\u00adben, dass Sie uns diese mit\u00adtei\u00adlen. Hier\u00adbei kann es sich z.B. um Daten han\u00addeln, die Sie in ein Kon\u00adtakt\u00adfor\u00admu\u00adlar eingeben.<\/p>\n\n\n\n<p>Andere Daten wer\u00adden auto\u00adma\u00adtisch beim Besuch der Web\u00adsite durch unsere IT-Sys\u00adteme erfasst. Das sind vor allem tech\u00adni\u00adsche Daten (z.B. Inter\u00adnet\u00adbrow\u00adser, Betriebs\u00adsys\u00adtem oder Uhr\u00adzeit des Sei\u00adten\u00adauf\u00adrufs). Die Erfas\u00adsung die\u00adser Daten erfolgt auto\u00adma\u00adtisch, sobald Sie unsere Web\u00adsite betreten.<\/p>\n\n\n\n<p><strong>Wof\u00fcr nut\u00adzen wir Ihre Daten?<br><\/strong>Ein Teil der Daten wird erho\u00adben, um eine feh\u00adler\u00adfreie Bereit\u00adstel\u00adlung der Web\u00adsite zu gew\u00e4hr\u00adleis\u00adten. Andere Daten k\u00f6n\u00adnen zur Ana\u00adlyse Ihres Nut\u00adzer\u00adver\u00adhal\u00adtens ver\u00adwen\u00addet werden.<\/p>\n\n\n\n<p><strong>Wel\u00adche Rechte haben Sie bez\u00fcg\u00adlich Ihrer Daten?<br><\/strong>Sie haben jeder\u00adzeit das Recht unent\u00adgelt\u00adlich Aus\u00adkunft \u00fcber Her\u00adkunft, Emp\u00adf\u00e4n\u00adger und Zweck Ihrer gespei\u00adcher\u00adten per\u00adso\u00adnen\u00adbe\u00adzo\u00adge\u00adnen Daten zu erhal\u00adten. Sie haben au\u00dfer\u00addem ein Recht, die Berich\u00adti\u00adgung, Sper\u00adrung oder L\u00f6schung die\u00adser Daten zu ver\u00adlan\u00adgen. Hierzu, sowie zu wei\u00adte\u00adren Fra\u00adgen zum Thema Daten\u00adschutz, k\u00f6n\u00adnen Sie sich jeder\u00adzeit unter der im Impres\u00adsum ange\u00adge\u00adbe\u00adnen Adresse an uns wen\u00adden. Des Wei\u00adte\u00adren steht Ihnen ein Beschwer\u00adde\u00adrecht bei der zust\u00e4n\u00addi\u00adgen Auf\u00adsichts\u00adbe\u00adh\u00f6rde&nbsp;zu.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">All\u00adge\u00admeine Hin\u00adweise und Pflichtinformationen<\/h3>\n\n\n\n<p><strong>Daten\u00adschutz<br><\/strong>Die Betrei\u00adber die\u00adser Sei\u00adten neh\u00admen den Schutz Ihrer per\u00ads\u00f6n\u00adli\u00adchen Daten sehr ernst. Wir behan\u00addeln Ihre per\u00adso\u00adnen\u00adbe\u00adzo\u00adge\u00adnen Daten ver\u00adtrau\u00adlich und ent\u00adspre\u00adchend der gesetz\u00adli\u00adchen Daten\u00adschutz\u00advor\u00adschrif\u00adten sowie die\u00adser Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<p>Wenn Sie diese Web\u00adsite benut\u00adzen, wer\u00adden ver\u00adschie\u00addene per\u00adso\u00adnen\u00adbe\u00adzo\u00adgene Daten erho\u00adben. Per\u00adso\u00adnen\u00adbe\u00adzo\u00adgene Daten sind Daten, mit denen Sie per\u00ads\u00f6n\u00adlich iden\u00adti\u00adfi\u00adziert wer\u00adden k\u00f6n\u00adnen. Die vor\u00adlie\u00adgende Daten\u00adschutz\u00ader\u00adkl\u00e4\u00adrung erl\u00e4u\u00adtert, wel\u00adche Daten wir erhe\u00adben und wof\u00fcr wir sie nut\u00adzen. Sie erl\u00e4u\u00adtert auch, wie und zu wel\u00adchem Zweck das geschieht.<\/p>\n\n\n\n<p>Wir wei\u00adsen dar\u00adauf hin, dass die Daten\u00ad\u00fcber\u00adtra\u00adgung im Inter\u00adnet (z.B. bei der Kom\u00admu\u00adni\u00adka\u00adtion per E\u2011Mail) Sicher\u00adheits\u00adl\u00fc\u00adcken auf\u00adwei\u00adsen kann. Ein l\u00fccken\u00adlo\u00adser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n\n\n\n<p><strong>Hin\u00adweis zur ver\u00adant\u00adwort\u00adli\u00adchen Stelle<br><\/strong>Die ver\u00adant\u00adwort\u00adli\u00adche Stelle f\u00fcr die Daten\u00adver\u00adar\u00adbei\u00adtung auf die\u00adser Web\u00adsite&nbsp;ist:<\/p>\n\n\n\n<p>Bianka Gr\u00e4f<br>Kin\u00adder\u00adta\u00adges\u00adpfle\u00adge\u00adper\u00adson<br>Oster\u00adberg\u00adstra\u00dfe 22<br>34246 Vell\u00admar<\/p>\n\n\n\n<p>Tele\u00adfon 0561\/8200634<\/p>\n\n\n\n<p><br><strong>Email<br><\/strong><a href=\"mailto:bg@tagesmutter-vellmar.de\">bg@\u200btagesmutter-\u200bvellmar.\u200bde<\/a><\/p>\n\n\n\n<p>Ver\u00adant\u00adwort\u00adli\u00adche Stelle ist die nat\u00fcr\u00adli\u00adche oder juris\u00adti\u00adsche Per\u00adson, die allein oder gemein\u00adsam mit ande\u00adren \u00fcber die Zwe\u00adcke und Mit\u00adtel der Ver\u00adar\u00adbei\u00adtung von per\u00adso\u00adnen\u00adbe\u00adzo\u00adge\u00adnen Daten (z.B. Namen, E\u2011Mail-Adres\u00adsen o. \u00c4.) entscheidet.<\/p>\n\n\n\n<p><strong>Wider\u00adruf Ihrer Ein\u00adwil\u00adli\u00adgung zur Daten\u00adver\u00adar\u00adbei\u00adtung<br><\/strong>Viele Daten\u00adver\u00adar\u00adbei\u00adtungs\u00advor\u00adg\u00e4nge sind nur mit Ihrer aus\u00addr\u00fcck\u00adli\u00adchen Ein\u00adwil\u00adli\u00adgung m\u00f6g\u00adlich. Sie k\u00f6n\u00adnen eine bereits erteilte Ein\u00adwil\u00adli\u00adgung jeder\u00adzeit wider\u00adru\u00adfen. Dazu reicht eine form\u00adlose Mit\u00adtei\u00adlung per E\u2011Mail an uns. Die Recht\u00adm\u00e4\u00ad\u00dfig\u00adkeit der bis zum Wider\u00adruf erfolg\u00adten Daten\u00adver\u00adar\u00adbei\u00adtung bleibt vom Wider\u00adruf unber\u00fchrt.<\/p>\n\n\n\n<p><strong>Beschwer\u00adde\u00adrecht bei der zust\u00e4n\u00addi\u00adgen Auf\u00adsichts\u00adbe\u00adh\u00f6rde<br><\/strong>Im Falle daten\u00adschutz\u00adrecht\u00adli\u00adcher Ver\u00adst\u00f6\u00dfe steht dem Betrof\u00adfe\u00adnen ein Beschwer\u00adde\u00adrecht bei der zust\u00e4n\u00addi\u00adgen Auf\u00adsichts\u00adbe\u00adh\u00f6rde zu. Zust\u00e4n\u00addige Auf\u00adsichts\u00adbe\u00adh\u00f6rde in daten\u00adschutz\u00adrecht\u00adli\u00adchen Fra\u00adgen ist der Lan\u00addes\u00adda\u00adten\u00adschutz\u00adbe\u00adauf\u00adtragte des Bun\u00addes\u00adlan\u00addes, in dem unser Unter\u00adneh\u00admen sei\u00adnen Sitz hat. Eine Liste der Daten\u00adschutz\u00adbe\u00adauf\u00adtrag\u00adten sowie deren Kon\u00adtakt\u00adda\u00adten k\u00f6n\u00adnen fol\u00adgen\u00addem Link ent\u00adnom\u00admen wer\u00adden:&nbsp;<a href=\"https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/\u200bwww\u200b.bfdi\u200b.bund\u200b.de\/\u200bD\u200bE\u200b\/\u200bI\u200bn\u200bf\u200bo\u200bt\u200bh\u200be\u200bk\u200b\/\u200bA\u200bn\u200bs\u200bc\u200bh\u200br\u200bi\u200bf\u200bt\u200be\u200bn\u200b_\u200bL\u200bi\u200bn\u200bk\u200bs\u200b\/\u200ba\u200bn\u200bs\u200bc\u200bh\u200br\u200bi\u200bf\u200bt\u200be\u200bn\u200b_\u200bl\u200bi\u200bn\u200bk\u200bs\u200b-\u200bn\u200bo\u200bd\u200be\u200b.\u200bh\u200btml<\/a>.<\/p>\n\n\n\n<p><strong>Recht auf Daten\u00ad\u00fcber\u00adtrag\u00adbar\u00adkeit<br><\/strong>Sie haben das Recht, Daten, die wir auf Grund\u00adlage Ihrer Ein\u00adwil\u00adli\u00adgung oder in Erf\u00fcl\u00adlung eines Ver\u00adtrags auto\u00adma\u00adti\u00adsiert ver\u00adar\u00adbei\u00adten, an sich oder an einen Drit\u00adten in einem g\u00e4n\u00adgi\u00adgen, maschi\u00adnen\u00adles\u00adba\u00adren For\u00admat aus\u00adh\u00e4n\u00addi\u00adgen zu las\u00adsen. Sofern Sie die direkte \u00dcber\u00adtra\u00adgung der Daten an einen ande\u00adren Ver\u00adant\u00adwort\u00adli\u00adchen ver\u00adlan\u00adgen, erfolgt dies nur, soweit es tech\u00adnisch mach\u00adbar&nbsp;ist.<\/p>\n\n\n\n<p><strong>SSL- bzw. TLS-Ver\u00adschl\u00fcs\u00adse\u00adlung<br><\/strong>Diese Seite nutzt aus Sicher\u00adheits\u00adgr\u00fcn\u00adden und zum Schutz der \u00dcber\u00adtra\u00adgung ver\u00adtrau\u00adli\u00adcher Inhalte, wie zum Bei\u00adspiel Bestel\u00adlun\u00adgen oder Anfra\u00adgen, die Sie an uns als Sei\u00adten\u00adbe\u00adtrei\u00adber sen\u00adden, eine SSL-bzw. TLS-Ver\u00adschl\u00fcs\u00adse\u00adlung. Eine ver\u00adschl\u00fcs\u00adselte Ver\u00adbin\u00addung erken\u00adnen Sie daran, dass die Adress\u00adzeile des Brow\u00adsers von \u201chttp:\/\/\u201d auf \u201chttps:\/\/\u201d wech\u00adselt und an dem Schloss-Sym\u00adbol in Ihrer Browserzeile.<\/p>\n\n\n\n<p>Wenn die SSL- bzw. TLS-Ver\u00adschl\u00fcs\u00adse\u00adlung akti\u00adviert ist, k\u00f6n\u00adnen die Daten, die Sie an uns \u00fcber\u00admit\u00adteln, nicht von Drit\u00adten mit\u00adge\u00adle\u00adsen werden.<\/p>\n\n\n\n<p><strong>Links zu ande\u00adren Web\u00adsei\u00adten<br><\/strong>Unser Inter\u00adnet-Ange\u00adbot ent\u00adh\u00e4lt Ver\u00adweise zu Inhal\u00adten ande\u00adrer Anbie\u00adter. Diese sind durch die Angabe expli\u00adzi\u00adter Links (z.B. www\u200b.inter\u200bnet\u200bseite\u200b.de), anhand ent\u00adspre\u00adchen\u00adder Hin\u00adweise im Text erkenn\u00adbar. Au\u00dfer\u00addem wer\u00adden externe Ver\u00adweise in einem eige\u00adnen Brow\u00adser\u00adfens\u00adter ge\u00f6ff\u00adnet. Die Nut\u00adzung die\u00adser frem\u00adden Inhalte unter\u00adliegt gege\u00adbe\u00adnen\u00adfalls ande\u00adren Vor\u00adga\u00adben als den hier dargestellten.<\/p>\n\n\n\n<p><strong>Aus\u00adkunft, Sper\u00adrung, L\u00f6schung<br><\/strong>Sie haben im Rah\u00admen der gel\u00adten\u00adden gesetz\u00adli\u00adchen Bestim\u00admun\u00adgen jeder\u00adzeit das Recht auf unent\u00adgelt\u00adli\u00adche Aus\u00adkunft \u00fcber Ihre gespei\u00adcher\u00adten per\u00adso\u00adnen\u00adbe\u00adzo\u00adge\u00adnen Daten, deren Her\u00adkunft und Emp\u00adf\u00e4n\u00adger und den Zweck der Daten\u00adver\u00adar\u00adbei\u00adtung und ggf. ein Recht auf Berich\u00adti\u00adgung, Sper\u00adrung oder L\u00f6schung die\u00adser Daten. Hierzu sowie zu wei\u00adte\u00adren Fra\u00adgen zum Thema per\u00adso\u00adnen\u00adbe\u00adzo\u00adgene Daten k\u00f6n\u00adnen Sie sich jeder\u00adzeit unter der im Impres\u00adsum ange\u00adge\u00adbe\u00adnen Adresse an uns wenden.<\/p>\n\n\n\n<p><strong>Wider\u00adspruch gegen Werbe-Mails<br><\/strong>Der Nut\u00adzung von im Rah\u00admen der Impres\u00adsums\u00adpflicht ver\u00ad\u00f6f\u00adfent\u00adlich\u00adten Kon\u00adtakt\u00adda\u00adten zur \u00dcber\u00adsen\u00addung von nicht aus\u00addr\u00fcck\u00adlich ange\u00adfor\u00adder\u00adter Wer\u00adbung und Infor\u00adma\u00adti\u00adons\u00adma\u00adte\u00adria\u00adlien wird hier\u00admit wider\u00adspro\u00adchen. Die Betrei\u00adber der Sei\u00adten behal\u00adten sich aus\u00addr\u00fcck\u00adlich recht\u00adli\u00adche Schritte im Falle der unver\u00adlang\u00adten Zusen\u00addung von Wer\u00adbe\u00adinfor\u00adma\u00adtio\u00adnen, etwa durch Spam-E-Mails, vor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Daten\u00ader\u00adfas\u00adsung auf unse\u00adrer Website<\/h3>\n\n\n\n<p><strong>Coo\u00adkies<br><\/strong>Die Inter\u00adnet\u00adsei\u00adten ver\u00adwen\u00adden teil\u00adweise soge\u00adnannte Coo\u00adkies. Coo\u00adkies rich\u00adten auf Ihrem Rech\u00adner kei\u00adnen Scha\u00adden an und ent\u00adhal\u00adten keine Viren. Coo\u00adkies die\u00adnen dazu, unser Ange\u00adbot nut\u00adzer\u00adfreund\u00adli\u00adcher, effek\u00adti\u00adver und siche\u00adrer zu machen. Coo\u00adkies sind kleine Text\u00adda\u00adteien, die auf Ihrem Rech\u00adner abge\u00adlegt wer\u00adden und die Ihr Brow\u00adser speichert.<\/p>\n\n\n\n<p>Die meis\u00adten der von uns ver\u00adwen\u00adde\u00adten Coo\u00adkies sind soge\u00adnannte \u201cSes\u00adsion-Coo\u00adkies\u201d. Sie wer\u00adden nach Ende Ihres Besuchs auto\u00adma\u00adtisch gel\u00f6scht. Andere Coo\u00adkies blei\u00adben auf Ihrem End\u00adge\u00adr\u00e4t gespei\u00adchert bis Sie diese l\u00f6schen. Diese Coo\u00adkies erm\u00f6g\u00adli\u00adchen es uns, Ihren Brow\u00adser beim n\u00e4chs\u00adten Besuch wiederzuerkennen.<\/p>\n\n\n\n<p>Sie k\u00f6n\u00adnen Ihren Brow\u00adser so ein\u00adstel\u00adlen, dass Sie \u00fcber das Set\u00adzen von Coo\u00adkies infor\u00admiert wer\u00adden und Coo\u00adkies nur im Ein\u00adzel\u00adfall erlau\u00adben, die Annahme von Coo\u00adkies f\u00fcr bestimmte F\u00e4lle oder gene\u00adrell aus\u00adschlie\u00ad\u00dfen sowie das auto\u00adma\u00adti\u00adsche L\u00f6schen der Coo\u00adkies beim Schlie\u00ad\u00dfen des Brow\u00adsers akti\u00advie\u00adren. Bei der Deak\u00adti\u00advie\u00adrung von Coo\u00adkies kann die Funk\u00adtio\u00adna\u00adli\u00adt\u00e4t die\u00adser Web\u00adsite ein\u00adge\u00adschr\u00e4nkt sein.<\/p>\n\n\n\n<p>Coo\u00adkies, die zur Durch\u00adf\u00fch\u00adrung des elek\u00adtro\u00adni\u00adschen Kom\u00admu\u00adni\u00adka\u00adti\u00adons\u00advor\u00adgangs oder zur Bereit\u00adstel\u00adlung bestimm\u00adter, von Ihnen erw\u00fcnsch\u00adter Funk\u00adtio\u00adnen (z.B. Waren\u00adkorb\u00adfunk\u00adtion) erfor\u00adder\u00adlich sind, wer\u00adden auf Grund\u00adlage von Art. 6&nbsp;Abs. 1&nbsp;lit. f&nbsp;DSGVO gespei\u00adchert. Der Web\u00adsite\u00adbe\u00adtrei\u00adber hat ein berech\u00adtig\u00adtes Inter\u00adesse an der Spei\u00adche\u00adrung von Coo\u00adkies zur tech\u00adnisch feh\u00adler\u00adfreien und opti\u00admier\u00adten Bereit\u00adstel\u00adlung sei\u00adner Dienste. Soweit andere Coo\u00adkies (z.B. Coo\u00adkies zur Ana\u00adlyse Ihres Surf\u00adver\u00adhal\u00adtens) gespei\u00adchert wer\u00adden, wer\u00adden diese in die\u00adser Daten\u00adschutz\u00ader\u00adkl\u00e4\u00adrung geson\u00addert behandelt.<\/p>\n\n\n\n<p><strong>Ser\u00adver-Log-Dateien<br><\/strong>Der Pro\u00advi\u00adder der Sei\u00adten erhebt und spei\u00adchert auto\u00adma\u00adtisch Infor\u00adma\u00adtio\u00adnen in soge\u00adnann\u00adten Ser\u00adver-Log-Dateien, die Ihr Brow\u00adser auto\u00adma\u00adtisch an uns \u00fcber\u00admit\u00adtelt. Dies&nbsp;sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Brow\u00adser\u00adtyp und Browserversion<\/li>\n\n\n\n<li>ver\u00adwen\u00adde\u00adtes Betriebssystem<\/li>\n\n\n\n<li>Refer\u00adrer&nbsp;URL<\/li>\n\n\n\n<li>Host\u00adname des zugrei\u00adfen\u00adden Rechners<\/li>\n\n\n\n<li>Uhr\u00adzeit der Serveranfrage<\/li>\n\n\n\n<li>IP-Adresse<\/li>\n<\/ul>\n\n\n\n<p>Eine Zusam\u00admen\u00adf\u00fch\u00adrung die\u00adser Daten mit ande\u00adren Daten\u00adquel\u00adlen wird nicht vorgenommen.<\/p>\n\n\n\n<p>Grund\u00adlage f\u00fcr die Daten\u00adver\u00adar\u00adbei\u00adtung ist Art. 6&nbsp;Abs. 1&nbsp;lit. b&nbsp;DSGVO, der die Ver\u00adar\u00adbei\u00adtung von Daten zur Erf\u00fcl\u00adlung eines Ver\u00adtrags oder vor\u00adver\u00adtrag\u00adli\u00adcher Ma\u00df\u00adnah\u00admen gestattet.<\/p>\n\n\n\n<p><strong>Kon\u00adtakt\u00adfor\u00admu\u00adlar<br><\/strong>Wenn Sie uns per Kon\u00adtakt\u00adfor\u00admu\u00adlar Anfra\u00adgen zukom\u00admen las\u00adsen, wer\u00adden Ihre Anga\u00adben aus dem Anfra\u00adge\u00adfor\u00admu\u00adlar inklu\u00adsive der von Ihnen dort ange\u00adge\u00adbe\u00adnen Kon\u00adtakt\u00adda\u00adten zwecks Bear\u00adbei\u00adtung der Anfrage und f\u00fcr den Fall von Anschluss\u00adfra\u00adgen bei uns gespei\u00adchert. Diese Daten geben wir nicht ohne Ihre Ein\u00adwil\u00adli\u00adgung weiter.<\/p>\n\n\n\n<p>Die Ver\u00adar\u00adbei\u00adtung der in das Kon\u00adtakt\u00adfor\u00admu\u00adlar ein\u00adge\u00adge\u00adbe\u00adnen Daten erfolgt somit aus\u00adschlie\u00df\u00adlich auf Grund\u00adlage Ihrer Ein\u00adwil\u00adli\u00adgung (Art. 6&nbsp;Abs. 1&nbsp;lit. a&nbsp;DSGVO). Sie k\u00f6n\u00adnen diese Ein\u00adwil\u00adli\u00adgung jeder\u00adzeit wider\u00adru\u00adfen. Dazu reicht eine form\u00adlose Mit\u00adtei\u00adlung per E\u2011Mail an uns. Die Recht\u00adm\u00e4\u00ad\u00dfig\u00adkeit der bis zum Wider\u00adruf erfolg\u00adten Daten\u00adver\u00adar\u00adbei\u00adtungs\u00advor\u00adg\u00e4nge bleibt vom Wider\u00adruf unber\u00fchrt.<\/p>\n\n\n\n<p>Die von Ihnen im Kon\u00adtakt\u00adfor\u00admu\u00adlar ein\u00adge\u00adge\u00adbe\u00adnen Daten ver\u00adblei\u00adben bei uns, bis Sie uns zur L\u00f6schung auf\u00adfor\u00addern, Ihre Ein\u00adwil\u00adli\u00adgung zur Spei\u00adche\u00adrung wider\u00adru\u00adfen oder der Zweck f\u00fcr die Daten\u00adspei\u00adche\u00adrung ent\u00adf\u00e4llt (z.B. nach abge\u00adschlos\u00adse\u00adner Bear\u00adbei\u00adtung Ihrer Anfrage). Zwin\u00adgende gesetz\u00adli\u00adche Bestim\u00admun\u00adgen \u2013 ins\u00adbe\u00adson\u00addere Auf\u00adbe\u00adwah\u00adrungs\u00adfris\u00adten \u2013 blei\u00adben unber\u00fchrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Soziale Medien<\/h3>\n\n\n\n<p><strong>Inhalte tei\u00adlen \u00fcber Plug\u00adins (Face\u00adbook, Google+1, X&nbsp;und andere.)<br><\/strong>Die Inhalte auf unse\u00adren Sei\u00adten k\u00f6n\u00adnen daten\u00adschutz\u00adkon\u00adform in sozia\u00adlen Netz\u00adwer\u00adken wie Face\u00adbook, X&nbsp;oder Google+ geteilt wer\u00adden. Ein direk\u00adter Kon\u00adtakt zwi\u00adschen den Netz\u00adwer\u00adken und Nut\u00adzern wird erst dann her\u00adge\u00adstellt, wenn der Nut\u00adzer aktiv auf einen die\u00adser But\u00adton klickt.<\/p>\n\n\n\n<p>Eine auto\u00adma\u00adti\u00adsche \u00dcber\u00adtra\u00adgung von Nut\u00adzer\u00adda\u00adten an die Betrei\u00adber die\u00adser Platt\u00adfor\u00admen erfolgt nicht. Ist der Nut\u00adzer bei einem der sozia\u00adlen Netz\u00adwerke ange\u00admel\u00addet, erscheint bei der Nut\u00adzung der Social-But\u00adtons von Face\u00adbook, Google+1, X&nbsp;und andere ein Infor\u00adma\u00adti\u00adons-Fens\u00adter, in dem der Nut\u00adzer den Text vor dem Absen\u00adden best\u00e4\u00adti\u00adgen&nbsp;kann.<\/p>\n\n\n\n<p>Unsere Nut\u00adzer k\u00f6n\u00adnen die Inhalte die\u00adser Seite daten\u00adschutz\u00adkon\u00adform in sozia\u00adlen Netz\u00adwer\u00adken tei\u00adlen, ohne dass kom\u00adplette Surf-Pro\u00adfile durch die Betrei\u00adber der Netz\u00adwerke erstellt werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Plug\u00adins und&nbsp;Tools<\/h3>\n\n\n\n<p><strong>Google Web Fonts<br><\/strong>Diese Seite nutzt zur ein\u00adheit\u00adli\u00adchen Dar\u00adstel\u00adlung von Schrift\u00adar\u00adten so genannte Web Fonts, die von Google bereit\u00adge\u00adstellt wer\u00adden. Beim Auf\u00adruf einer Seite l\u00e4dt Ihr Brow\u00adser die ben\u00f6\u00adtig\u00adten Web Fonts in ihren Brow\u00adser\u00adcache, um Texte und Schrift\u00adar\u00adten kor\u00adrekt anzuzeigen.<\/p>\n\n\n\n<p>Zu die\u00adsem Zweck muss der von Ihnen ver\u00adwen\u00addete Brow\u00adser Ver\u00adbin\u00addung zu den Ser\u00advern von Google auf\u00adneh\u00admen. Hier\u00addurch erlangt Google Kennt\u00adnis dar\u00ad\u00fcber, dass \u00fcber Ihre IP-Adresse unsere Web\u00adsite auf\u00adge\u00adru\u00adfen wurde. Die Nut\u00adzung von Google Web Fonts erfolgt im Inter\u00adesse einer ein\u00adheit\u00adli\u00adchen und anspre\u00adchen\u00adden Dar\u00adstel\u00adlung unse\u00adrer Online-Ange\u00adbote. Dies stellt ein berech\u00adtig\u00adtes Inter\u00adesse im Sinne von Art. 6&nbsp;Abs. 1&nbsp;lit. f&nbsp;DSGVO dar.<\/p>\n\n\n\n<p>Wenn Ihr Brow\u00adser Web Fonts nicht unter\u00adst\u00fctzt, wird eine Stan\u00addard\u00adschrift von Ihrem Com\u00adpu\u00adter genutzt.<\/p>\n\n\n\n<p>Wei\u00adtere Infor\u00adma\u00adtio\u00adnen zu Google Web Fonts fin\u00adden Sie unter:<br><a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/\u200bdeve\u200blo\u200bpers\u200b.google\u200b.com\/\u200bf\u200bo\u200bn\u200bt\u200bs\u200b\/\u200bfaq<\/a>&nbsp;und in der Daten\u00adschutz\u00ader\u00adkl\u00e4\u00adrung von Google:<br><a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/\u200bwww\u200b.google\u200b.com\/\u200bp\u200bo\u200bl\u200bi\u200bc\u200bi\u200be\u200bs\u200b\/\u200bp\u200br\u200bi\u200bv\u200ba\u200bcy\/<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daten\u00adschutz\u00ader\u00adkl\u00e4\u00adrung auf einen&nbsp;Blick All\u00adge\u00admeine Hin\u00adweiseDie fol\u00adgen\u00adden Hin\u00adweise geben einen ein\u00adfa\u00adchen \u00dcber\u00adblick dar\u00ad\u00fcber, was mit Ihren per\u00adso\u00adnen\u00adbe\u00adzo\u00adge\u00adnen Daten pas\u00adsiert, wenn Sie unsere Web\u00adsite besu\u00adchen. Per\u00adso\u00adnen\u00adbe\u00adzo\u00adgene Daten sind alle Daten, mit denen Sie per\u00ads\u00f6n\u00adlich iden\u00adti\u00adfi\u00adziert wer\u00adden k\u00f6n\u00adnen. Aus\u00adf\u00fchr\u00adli\u00adche Infor\u00adma\u00adtio\u00adnen zum Thema Daten\u00adschutz ent\u00adneh\u00admen Sie unse\u00adrer unter die\u00adsem Text auf\u00adge\u00adf\u00fchr\u00adten Daten\u00adschutz\u00ader\u00adkl\u00e4\u00adrung. Daten\u00ader\u00adfas\u00adsung auf unse\u00adrer Web\u00adsite Wer ist ver\u00adant\u00adwort\u00adlich f\u00fcr die Daten\u00ader\u00adfas\u00adsung auf die\u00adser Web\u00adsite?Die Daten\u00adver\u00adar\u00adbei\u00adtung auf die\u00adser Web\u00adsite erfolgt durch den Web\u00adsite\u00adbe\u00adtrei\u00adber. Des\u00adsen Kon\u00adtakt\u00adda\u00adten k\u00f6n\u00adnen Sie dem Impres\u00adsum die\u00adser Web\u00adsite ent\u00adneh\u00admen. Wie erfas\u00adsen wir Ihre Daten?Ihre Daten wer\u00adden zum einen dadurch erho\u00adben, dass Sie uns diese mit\u00adtei\u00adlen. Hier\u00adbei kann es sich z.B. um Daten han\u00addeln, die Sie in ein Kon\u00adtakt\u00adfor\u00admu\u00adlar ein\u00adge\u00adben. Andere Daten wer\u00adden auto\u00adma\u00adtisch beim Besuch der Web\u00adsite durch unsere IT-Sys\u00ad\u00adteme erfasst. Das sind vor allem tech\u00adni\u00adsche Daten (z.B. Inter\u00adnet\u00adbrow\u00adser, Betriebs\u00adsys\u00adtem oder Uhr\u00adzeit des Sei\u00adten\u00adauf\u00adrufs). Die Erfas\u00adsung die\u00adser Daten erfolgt auto\u00adma\u00adtisch, sobald Sie unsere Web\u00adsite betre\u00adten. Wof\u00fcr nut\u00adzen wir Ihre Daten?Ein Teil \u2026 <a href=\"https:\/\/tagesmutter-vellmar.de\/index.php\/datenschutzerklaerung\/\" class=\"more-link\"><span class=\"more-button\">Wei\u00adter\u00adle\u00adsen<span class=\"screen-reader-text\">Daten\u00adschutz\u00ader\u00adkl\u00e4\u00adrung<\/span><\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":7447,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"class_list":["post-7434","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/pages\/7434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/comments?post=7434"}],"version-history":[{"count":10,"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/pages\/7434\/revisions"}],"predecessor-version":[{"id":7544,"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/pages\/7434\/revisions\/7544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/media\/7447"}],"wp:attachment":[{"href":"https:\/\/tagesmutter-vellmar.de\/index.php\/wp-json\/wp\/v2\/media?parent=7434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}